{"id":28658,"date":"2021-05-03T11:15:42","date_gmt":"2021-05-03T14:15:42","guid":{"rendered":"http:\/\/192.168.200.48\/?p=28658"},"modified":"2021-11-09T12:06:07","modified_gmt":"2021-11-09T15:06:07","slug":"mantenimiento-estacional-en-la-zona-oeste","status":"publish","type":"post","link":"https:\/\/www.epen.gov.ar\/index.php\/2021\/05\/03\/mantenimiento-estacional-en-la-zona-oeste\/","title":{"rendered":"Mantenimiento estacional en la zona oeste"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_2_3 2_3 fusion-two-third fusion-column-first\" style=\"--awb-bg-size:cover;width:66.666666666667%;width:calc(66.666666666667% - ( ( 4% ) * 0.66666666666667 ) );margin-right: 4%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-text fusion-text-1\"><p style=\"text-align: justify;\"><em><strong>Los trabajos se ejecutar\u00e1n desde el martes 4 hasta el jueves 6. El jueves se producir\u00e1 un corte hacia Alumin\u00e9 de 13:30 a 18 horas. Con generaci\u00f3n local se abastecer\u00e1n servicios esenciales de dicha localidad.<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\">El Ente Provincial de Energ\u00eda del Neuqu\u00e9n (EPEN) dependiente de la Secretar\u00eda General y Servicios P\u00fablicos informa que se han programado trabajos de mantenimiento para los d\u00edas martes 4, mi\u00e9rcoles 5 y jueves 6 de mayo sobre el tramo de L\u00ednea de Media Tensi\u00f3n 33 kilovolt que va desde la \u201cBifurcaci\u00f3n\u201d hacia Villa Pehuenia y Alumin\u00e9, en el oeste provincial. Siguiendo protocolos de salud y seguridad en cada instancia, las tareas se desarrollar\u00e1n los d\u00edas planificados, en el horario de 13:30 a 18 horas.<\/p>\n<p style=\"text-align: justify;\">No obstante, se dispondr\u00e1n equipos de generaci\u00f3n a nivel local para cubrir la demanda energ\u00e9tica de ambas localidades durante los trabajos. Tanto el d\u00eda martes como el mi\u00e9rcoles, en Villa Pehuenia como hacia Moquehue, quedar\u00e1 abastecida la totalidad del consumo. En tanto, el jueves 6 de mayo para las tareas sobre la l\u00ednea hacia Alumin\u00e9, la generaci\u00f3n cubrir\u00e1 los servicios esenciales, durante dicho lapso.<\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_3 1_3 fusion-one-third fusion-column-last\" style=\"--awb-bg-size:cover;width:33.333333333333%;width:calc(33.333333333333% - ( ( 4% ) * 0.33333333333333 ) );\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-widget-area awb-widget-area-element fusion-widget-area-1 fusion-content-widget-area\" style=\"--awb-title-size:20px;--awb-title-color:#333333;--awb-padding:0px 0px 0px 0px;\"><style type=\"text\/css\" data-id=\"tweets-widget-2\">#tweets-widget-2 li { border-color:#eaeaea;}<\/style><section id=\"tweets-widget-2\" class=\"widget tweets\" style=\"border-style: solid;border-color: #eaeaea;border-color:transparent;border-width:0px;\">\t\t\t\t\n\t\t<div style=\"overflow:hidden\">\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"twitter-timeline\" data-dnt=\"true\" href=\"https:\/\/twitter.com\/@EPEN_Informa\" data-width=\"500\" data-height=\"300\" width=\"500\" height=\"300\" data-theme=\"light\" data-link-color=\"##25a9bd\" data-border-color=\"#eaeaea\" data-chrome=\"\">Tweets por @EPEN_Informa<\/a>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<script async src=\"\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n\t\t\t\t\t\t\t\n\t\t<\/div>\n\t\t<\/section>\n\t\t<section id=\"recent-posts-3\" class=\"widget widget_recent_entries\" style=\"border-style: solid;border-color:transparent;border-width:0px;\">\n\t\t<div class=\"heading\"><h4 class=\"widget-title\">Entradas recientes<\/h4><\/div>\n\t\t<ul>\n\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t<a href=\"https:\/\/www.epen.gov.ar\/index.php\/2026\/05\/13\/licitacion-publica-n-o-15-2026-adquisicion-de-materiales-para-funcionamiento-rubro-columnas-de-hormigon\/\">LICITACI\u00d3N PUBLICA N.\u00ba 15\/2026- \u00abADQUISICI\u00d3N DE MATERIALES PARA FUNCIONAMIENTO, RUBRO: COLUMNAS DE HORMIG\u00d3N\u00bb<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"post-date\">13\/05\/2026<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t<a href=\"https:\/\/www.epen.gov.ar\/index.php\/2026\/05\/12\/corte-programado-en-sectores-de-villa-la-angostura-el-13-y-14-05-2026\/\">Corte Programado en sectores de Villa La Angostura el 13 y 14\/05\/2026<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"post-date\">12\/05\/2026<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t<a href=\"https:\/\/www.epen.gov.ar\/index.php\/2026\/05\/11\/corte-programado-en-sectores-de-anelo-el-12-05-2026\/\">Corte Programado en sectores de A\u00f1elo el 12\/05\/2026<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"post-date\">11\/05\/2026<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t<a href=\"https:\/\/www.epen.gov.ar\/index.php\/2026\/05\/11\/corte-programado-en-sectores-de-centenario-el-12-05-2026\/\">Corte Programado en sectores de Centenario el 12\/05\/2026<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"post-date\">11\/05\/2026<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t<a href=\"https:\/\/www.epen.gov.ar\/index.php\/2026\/05\/11\/corte-programado-en-varvarco-y-manzano-amargo-el-13-05-26\/\">Corte Programado en Varvarco y Manzano Amargo el 13\/05\/26<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"post-date\">11\/05\/2026<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t<\/ul>\n\n\t\t<\/section><div class=\"fusion-additional-widget-content\"><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":4111,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[84],"tags":[145],"class_list":["post-28658","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-seguridad-publica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>EPEN - Mantenimiento estacional en la zona oeste<\/title>\n<meta name=\"description\" content=\"Mantenimiento estacional en la zona oeste\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.epen.gov.ar\/index.php\/2021\/05\/03\/mantenimiento-estacional-en-la-zona-oeste\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EPEN - Mantenimiento estacional en la zona oeste\" \/>\n<meta property=\"og:description\" content=\"Mantenimiento estacional en la zona oeste\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.epen.gov.ar\/index.php\/2021\/05\/03\/mantenimiento-estacional-en-la-zona-oeste\/\" \/>\n<meta property=\"og:site_name\" content=\"EPEN\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EPEN.Neuquen\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-03T14:15:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-09T15:06:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.epen.gov.ar\/wp-content\/uploads\/2019\/07\/reparacion-de-linea.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1068\" \/>\n\t<meta property=\"og:image:height\" content=\"528\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Prensa EPEN\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EPEN_Informa\" \/>\n<meta name=\"twitter:site\" content=\"@EPEN_Informa\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Prensa EPEN\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.epen.gov.ar\/index.php\/2021\/05\/03\/mantenimiento-estacional-en-la-zona-oeste\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.epen.gov.ar\/index.php\/2021\/05\/03\/mantenimiento-estacional-en-la-zona-oeste\/\"},\"author\":{\"name\":\"Prensa EPEN\",\"@id\":\"https:\/\/www.epen.gov.ar\/#\/schema\/person\/ce6cff87c2fc01264becc10fa105ad4f\"},\"headline\":\"Mantenimiento estacional en la zona oeste\",\"datePublished\":\"2021-05-03T14:15:42+00:00\",\"dateModified\":\"2021-11-09T15:06:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.epen.gov.ar\/index.php\/2021\/05\/03\/mantenimiento-estacional-en-la-zona-oeste\/\"},\"wordCount\":622,\"publisher\":{\"@id\":\"https:\/\/www.epen.gov.ar\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.epen.gov.ar\/index.php\/2021\/05\/03\/mantenimiento-estacional-en-la-zona-oeste\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.epen.gov.ar\/wp-content\/uploads\/2019\/07\/reparacion-de-linea.jpg\",\"keywords\":[\"Seguridad Publica\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.epen.gov.ar\/index.php\/2021\/05\/03\/mantenimiento-estacional-en-la-zona-oeste\/\",\"url\":\"https:\/\/www.epen.gov.ar\/index.php\/2021\/05\/03\/mantenimiento-estacional-en-la-zona-oeste\/\",\"name\":\"EPEN - Mantenimiento estacional en la zona oeste\",\"isPartOf\":{\"@id\":\"https:\/\/www.epen.gov.ar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.epen.gov.ar\/index.php\/2021\/05\/03\/mantenimiento-estacional-en-la-zona-oeste\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.epen.gov.ar\/index.php\/2021\/05\/03\/mantenimiento-estacional-en-la-zona-oeste\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.epen.gov.ar\/wp-content\/uploads\/2019\/07\/reparacion-de-linea.jpg\",\"datePublished\":\"2021-05-03T14:15:42+00:00\",\"dateModified\":\"2021-11-09T15:06:07+00:00\",\"description\":\"Mantenimiento estacional en la zona oeste\",\"breadcrumb\":{\"@id\":\"https:\/\/www.epen.gov.ar\/index.php\/2021\/05\/03\/mantenimiento-estacional-en-la-zona-oeste\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.epen.gov.ar\/index.php\/2021\/05\/03\/mantenimiento-estacional-en-la-zona-oeste\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.epen.gov.ar\/index.php\/2021\/05\/03\/mantenimiento-estacional-en-la-zona-oeste\/#primaryimage\",\"url\":\"https:\/\/www.epen.gov.ar\/wp-content\/uploads\/2019\/07\/reparacion-de-linea.jpg\",\"contentUrl\":\"https:\/\/www.epen.gov.ar\/wp-content\/uploads\/2019\/07\/reparacion-de-linea.jpg\",\"width\":1068,\"height\":528},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.epen.gov.ar\/index.php\/2021\/05\/03\/mantenimiento-estacional-en-la-zona-oeste\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/www.epen.gov.ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mantenimiento estacional en la zona oeste\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.epen.gov.ar\/#website\",\"url\":\"https:\/\/www.epen.gov.ar\/\",\"name\":\"EPEN\",\"description\":\"Ente Provincial de Energ\u00eda del Neuqu\u00e9n\",\"publisher\":{\"@id\":\"https:\/\/www.epen.gov.ar\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.epen.gov.ar\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.epen.gov.ar\/#organization\",\"name\":\"Ente Provincial de Energ\u00eda del Neuqu\u00e9n\",\"url\":\"https:\/\/www.epen.gov.ar\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.epen.gov.ar\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.epen.gov.ar\/wp-content\/uploads\/2024\/02\/Logo-EPEN-2.jpg\",\"contentUrl\":\"https:\/\/www.epen.gov.ar\/wp-content\/uploads\/2024\/02\/Logo-EPEN-2.jpg\",\"width\":696,\"height\":696,\"caption\":\"Ente Provincial de Energ\u00eda del Neuqu\u00e9n\"},\"image\":{\"@id\":\"https:\/\/www.epen.gov.ar\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/EPEN.Neuquen\",\"https:\/\/x.com\/EPEN_Informa\",\"https:\/\/www.youtube.com\/@epenprensa7384\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.epen.gov.ar\/#\/schema\/person\/ce6cff87c2fc01264becc10fa105ad4f\",\"name\":\"Prensa EPEN\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/f8120b8688012ccf2d7fbcf7a970cfbabf0ab63b09c2dbd72c194bee080070e9?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f8120b8688012ccf2d7fbcf7a970cfbabf0ab63b09c2dbd72c194bee080070e9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f8120b8688012ccf2d7fbcf7a970cfbabf0ab63b09c2dbd72c194bee080070e9?s=96&d=mm&r=g\",\"caption\":\"Prensa EPEN\"},\"url\":\"https:\/\/www.epen.gov.ar\/index.php\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EPEN - Mantenimiento estacional en la zona oeste","description":"Mantenimiento estacional en la zona oeste","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.epen.gov.ar\/index.php\/2021\/05\/03\/mantenimiento-estacional-en-la-zona-oeste\/","og_locale":"es_ES","og_type":"article","og_title":"EPEN - Mantenimiento estacional en la zona oeste","og_description":"Mantenimiento estacional en la zona oeste","og_url":"https:\/\/www.epen.gov.ar\/index.php\/2021\/05\/03\/mantenimiento-estacional-en-la-zona-oeste\/","og_site_name":"EPEN","article_publisher":"https:\/\/www.facebook.com\/EPEN.Neuquen","article_published_time":"2021-05-03T14:15:42+00:00","article_modified_time":"2021-11-09T15:06:07+00:00","og_image":[{"width":1068,"height":528,"url":"https:\/\/www.epen.gov.ar\/wp-content\/uploads\/2019\/07\/reparacion-de-linea.jpg","type":"image\/jpeg"}],"author":"Prensa EPEN","twitter_card":"summary_large_image","twitter_creator":"@EPEN_Informa","twitter_site":"@EPEN_Informa","twitter_misc":{"Escrito por":"Prensa EPEN","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.epen.gov.ar\/index.php\/2021\/05\/03\/mantenimiento-estacional-en-la-zona-oeste\/#article","isPartOf":{"@id":"https:\/\/www.epen.gov.ar\/index.php\/2021\/05\/03\/mantenimiento-estacional-en-la-zona-oeste\/"},"author":{"name":"Prensa EPEN","@id":"https:\/\/www.epen.gov.ar\/#\/schema\/person\/ce6cff87c2fc01264becc10fa105ad4f"},"headline":"Mantenimiento estacional en la zona oeste","datePublished":"2021-05-03T14:15:42+00:00","dateModified":"2021-11-09T15:06:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.epen.gov.ar\/index.php\/2021\/05\/03\/mantenimiento-estacional-en-la-zona-oeste\/"},"wordCount":622,"publisher":{"@id":"https:\/\/www.epen.gov.ar\/#organization"},"image":{"@id":"https:\/\/www.epen.gov.ar\/index.php\/2021\/05\/03\/mantenimiento-estacional-en-la-zona-oeste\/#primaryimage"},"thumbnailUrl":"https:\/\/www.epen.gov.ar\/wp-content\/uploads\/2019\/07\/reparacion-de-linea.jpg","keywords":["Seguridad Publica"],"articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.epen.gov.ar\/index.php\/2021\/05\/03\/mantenimiento-estacional-en-la-zona-oeste\/","url":"https:\/\/www.epen.gov.ar\/index.php\/2021\/05\/03\/mantenimiento-estacional-en-la-zona-oeste\/","name":"EPEN - Mantenimiento estacional en la zona oeste","isPartOf":{"@id":"https:\/\/www.epen.gov.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.epen.gov.ar\/index.php\/2021\/05\/03\/mantenimiento-estacional-en-la-zona-oeste\/#primaryimage"},"image":{"@id":"https:\/\/www.epen.gov.ar\/index.php\/2021\/05\/03\/mantenimiento-estacional-en-la-zona-oeste\/#primaryimage"},"thumbnailUrl":"https:\/\/www.epen.gov.ar\/wp-content\/uploads\/2019\/07\/reparacion-de-linea.jpg","datePublished":"2021-05-03T14:15:42+00:00","dateModified":"2021-11-09T15:06:07+00:00","description":"Mantenimiento estacional en la zona oeste","breadcrumb":{"@id":"https:\/\/www.epen.gov.ar\/index.php\/2021\/05\/03\/mantenimiento-estacional-en-la-zona-oeste\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.epen.gov.ar\/index.php\/2021\/05\/03\/mantenimiento-estacional-en-la-zona-oeste\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.epen.gov.ar\/index.php\/2021\/05\/03\/mantenimiento-estacional-en-la-zona-oeste\/#primaryimage","url":"https:\/\/www.epen.gov.ar\/wp-content\/uploads\/2019\/07\/reparacion-de-linea.jpg","contentUrl":"https:\/\/www.epen.gov.ar\/wp-content\/uploads\/2019\/07\/reparacion-de-linea.jpg","width":1068,"height":528},{"@type":"BreadcrumbList","@id":"https:\/\/www.epen.gov.ar\/index.php\/2021\/05\/03\/mantenimiento-estacional-en-la-zona-oeste\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.epen.gov.ar\/"},{"@type":"ListItem","position":2,"name":"Mantenimiento estacional en la zona oeste"}]},{"@type":"WebSite","@id":"https:\/\/www.epen.gov.ar\/#website","url":"https:\/\/www.epen.gov.ar\/","name":"EPEN","description":"Ente Provincial de Energ\u00eda del Neuqu\u00e9n","publisher":{"@id":"https:\/\/www.epen.gov.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.epen.gov.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.epen.gov.ar\/#organization","name":"Ente Provincial de Energ\u00eda del Neuqu\u00e9n","url":"https:\/\/www.epen.gov.ar\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.epen.gov.ar\/#\/schema\/logo\/image\/","url":"https:\/\/www.epen.gov.ar\/wp-content\/uploads\/2024\/02\/Logo-EPEN-2.jpg","contentUrl":"https:\/\/www.epen.gov.ar\/wp-content\/uploads\/2024\/02\/Logo-EPEN-2.jpg","width":696,"height":696,"caption":"Ente Provincial de Energ\u00eda del Neuqu\u00e9n"},"image":{"@id":"https:\/\/www.epen.gov.ar\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EPEN.Neuquen","https:\/\/x.com\/EPEN_Informa","https:\/\/www.youtube.com\/@epenprensa7384"]},{"@type":"Person","@id":"https:\/\/www.epen.gov.ar\/#\/schema\/person\/ce6cff87c2fc01264becc10fa105ad4f","name":"Prensa EPEN","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/f8120b8688012ccf2d7fbcf7a970cfbabf0ab63b09c2dbd72c194bee080070e9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f8120b8688012ccf2d7fbcf7a970cfbabf0ab63b09c2dbd72c194bee080070e9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f8120b8688012ccf2d7fbcf7a970cfbabf0ab63b09c2dbd72c194bee080070e9?s=96&d=mm&r=g","caption":"Prensa EPEN"},"url":"https:\/\/www.epen.gov.ar\/index.php\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.epen.gov.ar\/index.php\/wp-json\/wp\/v2\/posts\/28658","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.epen.gov.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.epen.gov.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.epen.gov.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.epen.gov.ar\/index.php\/wp-json\/wp\/v2\/comments?post=28658"}],"version-history":[{"count":3,"href":"https:\/\/www.epen.gov.ar\/index.php\/wp-json\/wp\/v2\/posts\/28658\/revisions"}],"predecessor-version":[{"id":69345,"href":"https:\/\/www.epen.gov.ar\/index.php\/wp-json\/wp\/v2\/posts\/28658\/revisions\/69345"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.epen.gov.ar\/index.php\/wp-json\/wp\/v2\/media\/4111"}],"wp:attachment":[{"href":"https:\/\/www.epen.gov.ar\/index.php\/wp-json\/wp\/v2\/media?parent=28658"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.epen.gov.ar\/index.php\/wp-json\/wp\/v2\/categories?post=28658"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.epen.gov.ar\/index.php\/wp-json\/wp\/v2\/tags?post=28658"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}