{"id":100486,"date":"2023-04-17T08:13:30","date_gmt":"2023-04-17T11:13:30","guid":{"rendered":"http:\/\/192.168.200.48\/?p=100486"},"modified":"2023-04-17T10:17:19","modified_gmt":"2023-04-17T13:17:19","slug":"cortes-programados-en-alumine-norquinco-y-zonas-rurales-aledanas-el-19-y-20-04-23","status":"publish","type":"post","link":"https:\/\/www.epen.gov.ar\/index.php\/2023\/04\/17\/cortes-programados-en-alumine-norquinco-y-zonas-rurales-aledanas-el-19-y-20-04-23\/","title":{"rendered":"Cortes programados en Alumin\u00e9, \u00d1orquinco y zonas rurales aleda\u00f1as el 19 y 20\/04\/23"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_2_3 2_3 fusion-two-third fusion-column-first\" style=\"--awb-bg-size:cover;width:66.666666666667%;width:calc(66.666666666667% - ( ( 4% ) * 0.66666666666667 ) );margin-right: 4%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-text fusion-text-1\"><p style=\"text-align: justify;\">El Ente Provincial de Energ\u00eda del Neuqu\u00e9n (EPEN) dependiente de la Secretar\u00eda General y Servicios P\u00fablicos, informa que se realizar\u00e1n cortes de energ\u00eda el\u00e9ctrica los d\u00edas <strong>mi\u00e9rcoles 19 y jueves 20 de abril de 13 a 19 hs., <\/strong>para\u00a0realizar tareas de mantenimiento programado sobre la l\u00ednea de Media Tensi\u00f3n Bifurcaci\u00f3n-Alumin\u00e9. Durante dicho lapso se activar\u00e1n los grupos de generaci\u00f3n aislada para abastecer los servicios esenciales.<\/p>\n<p style=\"text-align: justify;\">Sectores afectados:<\/p>\n<ul style=\"text-align: justify;\">\n<li><strong>Alumin\u00e9, \u00d1orquinco y zonas rurales aleda\u00f1as<\/strong>.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Solicitamos a los usuarios de los sectores afectados tomar los recaudos necesarios a efectos de reducir los inconvenientes que la falta de energ\u00eda pudiese ocasionar.<\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_3 1_3 fusion-one-third fusion-column-last\" style=\"--awb-bg-size:cover;width:33.333333333333%;width:calc(33.333333333333% - ( ( 4% ) * 0.33333333333333 ) );\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-widget-area awb-widget-area-element fusion-widget-area-1 fusion-content-widget-area\" style=\"--awb-title-size:20px;--awb-title-color:#333333;--awb-padding:0px 0px 0px 0px;\"><style type=\"text\/css\" data-id=\"tweets-widget-2\">#tweets-widget-2 li { border-color:#eaeaea;}<\/style><section id=\"tweets-widget-2\" class=\"widget tweets\" style=\"border-style: solid;border-color: #eaeaea;border-color:transparent;border-width:0px;\">\t\t\t\t\n\t\t<div style=\"overflow:hidden\">\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"twitter-timeline\" data-dnt=\"true\" href=\"https:\/\/twitter.com\/@EPEN_Informa\" data-width=\"500\" data-height=\"300\" width=\"500\" height=\"300\" data-theme=\"light\" data-link-color=\"##25a9bd\" data-border-color=\"#eaeaea\" data-chrome=\"\">Tweets por @EPEN_Informa<\/a>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<script async src=\"\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n\t\t\t\t\t\t\t\n\t\t<\/div>\n\t\t<\/section>\n\t\t<section id=\"recent-posts-3\" class=\"widget widget_recent_entries\" style=\"border-style: solid;border-color:transparent;border-width:0px;\">\n\t\t<div class=\"heading\"><h4 class=\"widget-title\">Entradas recientes<\/h4><\/div>\n\t\t<ul>\n\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t<a href=\"https:\/\/www.epen.gov.ar\/index.php\/2026\/07\/13\/el-epen-informa-el-esquema-de-atencion-por-el-dia-de-las-trabajadoras-y-los-trabajadores-de-la-electricidad\/\">El EPEN informa el esquema de atenci\u00f3n por el D\u00eda de las Trabajadoras y los Trabajadores de la Electricidad<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"post-date\">13\/07\/2026<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t<a href=\"https:\/\/www.epen.gov.ar\/index.php\/2026\/07\/08\/corte-programado-en-sector-de-la-region-alto-neuquen\/\">Corte programado en sector de la regi\u00f3n Alto Neuqu\u00e9n<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"post-date\">08\/07\/2026<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t<a href=\"https:\/\/www.epen.gov.ar\/index.php\/2026\/07\/07\/corte-programado-en-bajada-del-agrio-el-8-7-26\/\">Corte programado en Bajada del Agrio el 8\/7\/26<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"post-date\">07\/07\/2026<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t<a href=\"https:\/\/www.epen.gov.ar\/index.php\/2026\/07\/03\/culmino-la-vinculacion-electrica-del-paso-internacional-mamuil-malal\/\">Culmin\u00f3 la vinculaci\u00f3n el\u00e9ctrica del paso internacional Mamuil Malal<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"post-date\">03\/07\/2026<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t<a href=\"https:\/\/www.epen.gov.ar\/index.php\/2026\/07\/02\/corte-programado-en-sectores-de-anelo-el-04-07-2026\/\">Corte Programado en sectores de A\u00f1elo el 04\/07\/2026<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"post-date\">02\/07\/2026<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t<\/ul>\n\n\t\t<\/section><div class=\"fusion-additional-widget-content\"><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[263],"tags":[157,490,285,159,487],"class_list":["post-100486","post","type-post","status-publish","format-standard","hentry","category-cortes-programados","tag-alumine","tag-bifurcacion-alumine","tag-cortes-programados","tag-mantenimiento","tag-norquinco"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>EPEN - Cortes programados en Alumin\u00e9, \u00d1orquinco y zonas rurales aleda\u00f1as el 19 y 20\/04\/23<\/title>\n<meta name=\"description\" content=\"Cortes programados en Alumin\u00e9, \u00d1orquinco y zonas rurales aleda\u00f1as el 19 y 20\/04\/23\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.epen.gov.ar\/index.php\/2023\/04\/17\/cortes-programados-en-alumine-norquinco-y-zonas-rurales-aledanas-el-19-y-20-04-23\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EPEN - Cortes programados en Alumin\u00e9, \u00d1orquinco y zonas rurales aleda\u00f1as el 19 y 20\/04\/23\" \/>\n<meta property=\"og:description\" content=\"Cortes programados en Alumin\u00e9, \u00d1orquinco y zonas rurales aleda\u00f1as el 19 y 20\/04\/23\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.epen.gov.ar\/index.php\/2023\/04\/17\/cortes-programados-en-alumine-norquinco-y-zonas-rurales-aledanas-el-19-y-20-04-23\/\" \/>\n<meta property=\"og:site_name\" content=\"EPEN\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EPEN.Neuquen\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-17T11:13:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-17T13:17:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.epen.gov.ar\/wp-content\/uploads\/2024\/02\/Logo-EPEN.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Prensa EPEN\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EPEN_Informa\" \/>\n<meta name=\"twitter:site\" content=\"@EPEN_Informa\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Prensa EPEN\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.epen.gov.ar\\\/index.php\\\/2023\\\/04\\\/17\\\/cortes-programados-en-alumine-norquinco-y-zonas-rurales-aledanas-el-19-y-20-04-23\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.epen.gov.ar\\\/index.php\\\/2023\\\/04\\\/17\\\/cortes-programados-en-alumine-norquinco-y-zonas-rurales-aledanas-el-19-y-20-04-23\\\/\"},\"author\":{\"name\":\"Prensa EPEN\",\"@id\":\"https:\\\/\\\/www.epen.gov.ar\\\/#\\\/schema\\\/person\\\/ce6cff87c2fc01264becc10fa105ad4f\"},\"headline\":\"Cortes programados en Alumin\u00e9, \u00d1orquinco y zonas rurales aleda\u00f1as el 19 y 20\\\/04\\\/23\",\"datePublished\":\"2023-04-17T11:13:30+00:00\",\"dateModified\":\"2023-04-17T13:17:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.epen.gov.ar\\\/index.php\\\/2023\\\/04\\\/17\\\/cortes-programados-en-alumine-norquinco-y-zonas-rurales-aledanas-el-19-y-20-04-23\\\/\"},\"wordCount\":555,\"publisher\":{\"@id\":\"https:\\\/\\\/www.epen.gov.ar\\\/#organization\"},\"keywords\":[\"Alumine\",\"Bifurcaci\u00f3n-Alumin\u00e9\",\"Cortes Programados\",\"Mantenimiento\",\"\u00d1orquinco\"],\"articleSection\":[\"Cortes Programados\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.epen.gov.ar\\\/index.php\\\/2023\\\/04\\\/17\\\/cortes-programados-en-alumine-norquinco-y-zonas-rurales-aledanas-el-19-y-20-04-23\\\/\",\"url\":\"https:\\\/\\\/www.epen.gov.ar\\\/index.php\\\/2023\\\/04\\\/17\\\/cortes-programados-en-alumine-norquinco-y-zonas-rurales-aledanas-el-19-y-20-04-23\\\/\",\"name\":\"EPEN - Cortes programados en Alumin\u00e9, \u00d1orquinco y zonas rurales aleda\u00f1as el 19 y 20\\\/04\\\/23\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.epen.gov.ar\\\/#website\"},\"datePublished\":\"2023-04-17T11:13:30+00:00\",\"dateModified\":\"2023-04-17T13:17:19+00:00\",\"description\":\"Cortes programados en Alumin\u00e9, \u00d1orquinco y zonas rurales aleda\u00f1as el 19 y 20\\\/04\\\/23\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.epen.gov.ar\\\/index.php\\\/2023\\\/04\\\/17\\\/cortes-programados-en-alumine-norquinco-y-zonas-rurales-aledanas-el-19-y-20-04-23\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.epen.gov.ar\\\/index.php\\\/2023\\\/04\\\/17\\\/cortes-programados-en-alumine-norquinco-y-zonas-rurales-aledanas-el-19-y-20-04-23\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.epen.gov.ar\\\/index.php\\\/2023\\\/04\\\/17\\\/cortes-programados-en-alumine-norquinco-y-zonas-rurales-aledanas-el-19-y-20-04-23\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.epen.gov.ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cortes programados en Alumin\u00e9, \u00d1orquinco y zonas rurales aleda\u00f1as el 19 y 20\\\/04\\\/23\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.epen.gov.ar\\\/#website\",\"url\":\"https:\\\/\\\/www.epen.gov.ar\\\/\",\"name\":\"EPEN\",\"description\":\"Ente Provincial de Energ\u00eda del Neuqu\u00e9n\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.epen.gov.ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.epen.gov.ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.epen.gov.ar\\\/#organization\",\"name\":\"Ente Provincial de Energ\u00eda del Neuqu\u00e9n\",\"url\":\"https:\\\/\\\/www.epen.gov.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.epen.gov.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.epen.gov.ar\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logo-EPEN-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.epen.gov.ar\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logo-EPEN-2.jpg\",\"width\":696,\"height\":696,\"caption\":\"Ente Provincial de Energ\u00eda del Neuqu\u00e9n\"},\"image\":{\"@id\":\"https:\\\/\\\/www.epen.gov.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EPEN.Neuquen\",\"https:\\\/\\\/x.com\\\/EPEN_Informa\",\"https:\\\/\\\/www.youtube.com\\\/@epenprensa7384\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.epen.gov.ar\\\/#\\\/schema\\\/person\\\/ce6cff87c2fc01264becc10fa105ad4f\",\"name\":\"Prensa EPEN\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f8120b8688012ccf2d7fbcf7a970cfbabf0ab63b09c2dbd72c194bee080070e9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f8120b8688012ccf2d7fbcf7a970cfbabf0ab63b09c2dbd72c194bee080070e9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f8120b8688012ccf2d7fbcf7a970cfbabf0ab63b09c2dbd72c194bee080070e9?s=96&d=mm&r=g\",\"caption\":\"Prensa EPEN\"},\"url\":\"https:\\\/\\\/www.epen.gov.ar\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EPEN - Cortes programados en Alumin\u00e9, \u00d1orquinco y zonas rurales aleda\u00f1as el 19 y 20\/04\/23","description":"Cortes programados en Alumin\u00e9, \u00d1orquinco y zonas rurales aleda\u00f1as el 19 y 20\/04\/23","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.epen.gov.ar\/index.php\/2023\/04\/17\/cortes-programados-en-alumine-norquinco-y-zonas-rurales-aledanas-el-19-y-20-04-23\/","og_locale":"es_ES","og_type":"article","og_title":"EPEN - Cortes programados en Alumin\u00e9, \u00d1orquinco y zonas rurales aleda\u00f1as el 19 y 20\/04\/23","og_description":"Cortes programados en Alumin\u00e9, \u00d1orquinco y zonas rurales aleda\u00f1as el 19 y 20\/04\/23","og_url":"https:\/\/www.epen.gov.ar\/index.php\/2023\/04\/17\/cortes-programados-en-alumine-norquinco-y-zonas-rurales-aledanas-el-19-y-20-04-23\/","og_site_name":"EPEN","article_publisher":"https:\/\/www.facebook.com\/EPEN.Neuquen","article_published_time":"2023-04-17T11:13:30+00:00","article_modified_time":"2023-04-17T13:17:19+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.epen.gov.ar\/wp-content\/uploads\/2024\/02\/Logo-EPEN.jpg","type":"image\/jpeg"}],"author":"Prensa EPEN","twitter_card":"summary_large_image","twitter_creator":"@EPEN_Informa","twitter_site":"@EPEN_Informa","twitter_misc":{"Escrito por":"Prensa EPEN","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.epen.gov.ar\/index.php\/2023\/04\/17\/cortes-programados-en-alumine-norquinco-y-zonas-rurales-aledanas-el-19-y-20-04-23\/#article","isPartOf":{"@id":"https:\/\/www.epen.gov.ar\/index.php\/2023\/04\/17\/cortes-programados-en-alumine-norquinco-y-zonas-rurales-aledanas-el-19-y-20-04-23\/"},"author":{"name":"Prensa EPEN","@id":"https:\/\/www.epen.gov.ar\/#\/schema\/person\/ce6cff87c2fc01264becc10fa105ad4f"},"headline":"Cortes programados en Alumin\u00e9, \u00d1orquinco y zonas rurales aleda\u00f1as el 19 y 20\/04\/23","datePublished":"2023-04-17T11:13:30+00:00","dateModified":"2023-04-17T13:17:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.epen.gov.ar\/index.php\/2023\/04\/17\/cortes-programados-en-alumine-norquinco-y-zonas-rurales-aledanas-el-19-y-20-04-23\/"},"wordCount":555,"publisher":{"@id":"https:\/\/www.epen.gov.ar\/#organization"},"keywords":["Alumine","Bifurcaci\u00f3n-Alumin\u00e9","Cortes Programados","Mantenimiento","\u00d1orquinco"],"articleSection":["Cortes Programados"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.epen.gov.ar\/index.php\/2023\/04\/17\/cortes-programados-en-alumine-norquinco-y-zonas-rurales-aledanas-el-19-y-20-04-23\/","url":"https:\/\/www.epen.gov.ar\/index.php\/2023\/04\/17\/cortes-programados-en-alumine-norquinco-y-zonas-rurales-aledanas-el-19-y-20-04-23\/","name":"EPEN - Cortes programados en Alumin\u00e9, \u00d1orquinco y zonas rurales aleda\u00f1as el 19 y 20\/04\/23","isPartOf":{"@id":"https:\/\/www.epen.gov.ar\/#website"},"datePublished":"2023-04-17T11:13:30+00:00","dateModified":"2023-04-17T13:17:19+00:00","description":"Cortes programados en Alumin\u00e9, \u00d1orquinco y zonas rurales aleda\u00f1as el 19 y 20\/04\/23","breadcrumb":{"@id":"https:\/\/www.epen.gov.ar\/index.php\/2023\/04\/17\/cortes-programados-en-alumine-norquinco-y-zonas-rurales-aledanas-el-19-y-20-04-23\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.epen.gov.ar\/index.php\/2023\/04\/17\/cortes-programados-en-alumine-norquinco-y-zonas-rurales-aledanas-el-19-y-20-04-23\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.epen.gov.ar\/index.php\/2023\/04\/17\/cortes-programados-en-alumine-norquinco-y-zonas-rurales-aledanas-el-19-y-20-04-23\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.epen.gov.ar\/"},{"@type":"ListItem","position":2,"name":"Cortes programados en Alumin\u00e9, \u00d1orquinco y zonas rurales aleda\u00f1as el 19 y 20\/04\/23"}]},{"@type":"WebSite","@id":"https:\/\/www.epen.gov.ar\/#website","url":"https:\/\/www.epen.gov.ar\/","name":"EPEN","description":"Ente Provincial de Energ\u00eda del Neuqu\u00e9n","publisher":{"@id":"https:\/\/www.epen.gov.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.epen.gov.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.epen.gov.ar\/#organization","name":"Ente Provincial de Energ\u00eda del Neuqu\u00e9n","url":"https:\/\/www.epen.gov.ar\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.epen.gov.ar\/#\/schema\/logo\/image\/","url":"https:\/\/www.epen.gov.ar\/wp-content\/uploads\/2024\/02\/Logo-EPEN-2.jpg","contentUrl":"https:\/\/www.epen.gov.ar\/wp-content\/uploads\/2024\/02\/Logo-EPEN-2.jpg","width":696,"height":696,"caption":"Ente Provincial de Energ\u00eda del Neuqu\u00e9n"},"image":{"@id":"https:\/\/www.epen.gov.ar\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EPEN.Neuquen","https:\/\/x.com\/EPEN_Informa","https:\/\/www.youtube.com\/@epenprensa7384"]},{"@type":"Person","@id":"https:\/\/www.epen.gov.ar\/#\/schema\/person\/ce6cff87c2fc01264becc10fa105ad4f","name":"Prensa EPEN","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/f8120b8688012ccf2d7fbcf7a970cfbabf0ab63b09c2dbd72c194bee080070e9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f8120b8688012ccf2d7fbcf7a970cfbabf0ab63b09c2dbd72c194bee080070e9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f8120b8688012ccf2d7fbcf7a970cfbabf0ab63b09c2dbd72c194bee080070e9?s=96&d=mm&r=g","caption":"Prensa EPEN"},"url":"https:\/\/www.epen.gov.ar\/index.php\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.epen.gov.ar\/index.php\/wp-json\/wp\/v2\/posts\/100486","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.epen.gov.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.epen.gov.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.epen.gov.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.epen.gov.ar\/index.php\/wp-json\/wp\/v2\/comments?post=100486"}],"version-history":[{"count":4,"href":"https:\/\/www.epen.gov.ar\/index.php\/wp-json\/wp\/v2\/posts\/100486\/revisions"}],"predecessor-version":[{"id":100512,"href":"https:\/\/www.epen.gov.ar\/index.php\/wp-json\/wp\/v2\/posts\/100486\/revisions\/100512"}],"wp:attachment":[{"href":"https:\/\/www.epen.gov.ar\/index.php\/wp-json\/wp\/v2\/media?parent=100486"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.epen.gov.ar\/index.php\/wp-json\/wp\/v2\/categories?post=100486"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.epen.gov.ar\/index.php\/wp-json\/wp\/v2\/tags?post=100486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}